{"id":395964,"date":"2025-04-04T14:14:12","date_gmt":"2025-04-04T14:14:12","guid":{"rendered":"https:\/\/pandorafms.com\/?p=395964"},"modified":"2026-01-27T09:21:57","modified_gmt":"2026-01-27T09:21:57","slug":"que-es-informatica-forense","status":"publish","type":"post","link":"https:\/\/pandorafms.com\/es\/it-topics\/que-es-informatica-forense\/","title":{"rendered":"\u00bfQu\u00e9 es la Inform\u00e1tica Forense? Gu\u00eda Completa de An\u00e1lisis Digital y Ciberseguridad"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbSection\u00bb _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb50px||||false|false\u00bb custom_css_main_element=\u00bbz-index:0!important;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||||false|false\u00bb sticky_position=\u00bbtop\u00bb sticky_offset_top=\u00bb100px\u00bb sticky_limit_bottom=\u00bbsection\u00bb motion_trigger_start=\u00bbtop\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbindice\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||0px||false|false\u00bb custom_padding=\u00bb||14px||false|false\u00bb link_option_url=\u00bb#1&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"font-size: 0.9em; line-height: 1.4em; color: #333333;\"><strong>Secciones<\/strong><\/p>\n<ul class=\"ittopicsul\">\n<li><a href=\"#1\">Definici\u00f3n y relevancia en ciberseguridad<\/a><\/li>\n<li><a href=\"#2\">Evoluci\u00f3n de la inform\u00e1tica forense<\/a><\/li>\n<li><a href=\"#3\">Principios fundamentales<\/a><\/li>\n<li><a href=\"#4\">Aplicaciones en ciberseguridad y resoluci\u00f3n de incidentes<\/a><\/li>\n<li><a href=\"#5\">Fases de una investigaci\u00f3n forense digital<\/a><\/li>\n<li><a href=\"#6\">Desaf\u00edos actuales en inform\u00e1tica forense<\/a><\/li>\n<li><a href=\"#7\">Herramientas y t\u00e9cnicas clave<\/a><\/li>\n<li><a href=\"#8\">Integraci\u00f3n con la respuesta a incidentes (DFIR)<\/a><\/li>\n<li><a href=\"#9\">El rol de Pandora FMS en la inform\u00e1tica forense<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_css_main_element=\u00bbz-index:0!important;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbseccion\u00bb module_id=\u00bb1&#8243; module_class=\u00bbittopicscontent\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb z_index=\u00bb0&#8243; custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbfont-family:%22Pandora-Light%22;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 id=\"1\">Definici\u00f3n y relevancia en ciberseguridad<\/h2>\n<p>La inform\u00e1tica forense (cyber forensics, digital forensics o <a href=\"https:\/\/www.techtarget.com\/searchsecurity\/definition\/computer-forensics\" target=\"_blank\" rel=\"nofollow noopener\">computer forensics<\/A>) es el uso de t\u00e9cnicas especializadas para recopilar, analizar e investigar datos obtenidos de dispositivos electr\u00f3nicos (incluyendo archivos borrados y recuperados) y actividades cibern\u00e9ticas. Su objetivo es llevar a cabo una investigaci\u00f3n estructurada, usando evidencia documentada, que ayude a comprender exactamente qu\u00e9 sucedi\u00f3 en un dispositivo inform\u00e1tico y qui\u00e9n fue responsable del evento o incidente de seguridad.<\/p>\n<h3>Diferencias con la ciberseguridad tradicional<\/h3>\n<p>La inform\u00e1tica forense se diferencia esencialmente de la ciberseguridad tradicional en que se implementa la recuperaci\u00f3n de datos con pautas de cumplimiento legal para que los hallazgos sean admisibles en procedimientos legales. Tambi\u00e9n, esta investigaci\u00f3n forense procura la recopilaci\u00f3n de la informaci\u00f3n de manera que se preserve su integridad, ayudando a los investigadores a analizar los datos o el sistema en cuesti\u00f3n para determinar si existi\u00f3 alguna modificaci\u00f3n, como sucedi\u00f3 y qui\u00e9n la realiz\u00f3.<\/p>\n<h2 id=\"2\">Evoluci\u00f3n de la inform\u00e1tica forense<\/h2>\n<h3>Origen y desarrollo<\/h3>\n<p>Para los expertos en este tema, es dif\u00edcil ubicar el origen exacto de la inform\u00e1tica forense o se\u00f1alar el primer examen forense inform\u00e1tico, aunque coinciden en que evolucion\u00f3 desde los a\u00f1os 70 cuando se comenz\u00f3 a usar t\u00e9cnicas para examinar equipos de c\u00f3mputo en busca de evidencias digitales. Los hitos m\u00e1s importantes son:<\/p>\n<ul class=\"lista\">\n<li><a href=\"https:\/\/www.graytips.com\/cyber-forensics\/brief-history-of-computer-forensics\/\" target=\"_blank\" rel=\"nofollow noopener\">Michael Anderson<\/a> (agente especial del Servicio de Impuestos Internos de Estados Unidos) se le considera como el padre de la inform\u00e1tica forense, cuando impuls\u00f3 el estudio del almacenamiento, la p\u00e9rdida y el robo de datos en 1988.<\/li>\n<li>En los 80s, los investigadores financieros y los tribunales se dan cuenta de que, en muchos casos, los registros y las pruebas estaban \u00fanicamente en las computadoras.<\/li>\n<li>La empresa Norton DiskEdit implement\u00f3 una herramienta para hallar archivos eliminados.<\/li>\n<li>La <a href=\"https:\/\/acfe-spain.com\/acfe-que-es\" target=\"_blank\" rel=\"nofollow noopener\">Asociaci\u00f3n de Examinadores de Fraude Certificados<\/a> comenz\u00f3 a capacitar a su personal en inform\u00e1tica forense.<\/li>\n<\/ul>\n<p>Desde entonces, la inform\u00e1tica forense ha evolucionado constantemente para contrarrestar el cibercrimen con recursos y t\u00e9cnicas m\u00e1s sofisticadas, junto con regulaciones y normativas encaminadas a la labor forense digital.<\/p>\n<h3>Regulaciones y normativas clave<\/h3>\n<p>A lo largo de la evoluci\u00f3n de la inform\u00e1tica forense, han surgido regulaciones y normativas. Es importante que te familiarices con las que son clave para garantizar la integridad de las pruebas y la protecci\u00f3n de los derechos de uso de los datos, tales como:<\/p>\n<ul class=\"lista\">\n<li><strong>Est\u00e1ndares internacionales: <\/strong>como actualizaciones de software o hardware, migraciones a la nube, implementaci\u00f3n de nuevas herramientas&#8230;\n<ul class=\"lista\">\n<li><a href=\"https:\/\/ciberseguridad.com\/normativa\/espana\/iso-iec-27037-evidencia-digital\/\" target=\"_blank\" rel=\"nofollow noopener\">ISO\/IEC 27037<\/a> &#8211; Mejores pr\u00e1cticas mundiales para la identificaci\u00f3n, recopilaci\u00f3n, adquisici\u00f3n y preservaci\u00f3n de la evidencia digital.<\/li>\n<li><a href=\"https:\/\/csrc.nist.gov\/pubs\/sp\/800\/86\/final\" target=\"_blank\" rel=\"nofollow noopener\">NIST SP 800-86<\/a> &#8211; El an\u00e1lisis de evidencia forense digital usado por acad\u00e9micos y profesionales.<\/li>\n<li><a href=\"https:\/\/www.iso.org\/standard\/53241.html\" target=\"_blank\" rel=\"nofollow noopener\">ISO\/IEC 30121:2015<\/a> &#8211; Un marco de gobernanza para gestionar los riesgos forenses digitales.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Cadena de custodia (<a href=\"https:\/\/www.geeksforgeeks.org\/chain-of-custody-digital-forensics\/\" target=\"_blank\" rel=\"nofollow noopener\">Chain of Custody<\/a>):<\/strong> regulaciones sobre el mantenimiento de una cadena de custodia clara que garantice la evidencia intacta, con calidad y admisible ante la ley, con base en:\n<ul class=\"lista\">\n<li>Recopilaci\u00f3n de evidencia digital (detalle, la hora, la fecha y la condici\u00f3n del dispositivo).<\/li>\n<li>Im\u00e1genes y an\u00e1lisis, con una r\u00e9plica exacta del disco duro del dispositivo para obtener evidencia intacta e \u00edntegra.<\/li>\n<li>Documentaci\u00f3n de transferencias (por ejemplo, de un t\u00e9cnico a un analista) con detalles como el prop\u00f3sito, la fecha y la hora.<\/li>\n<li>Presentaci\u00f3n en la sala del tribunal con evidencia de que no ha sido alterada ni manipulada.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Cooperaci\u00f3n transfronteriza:<\/strong> regulaciones entre pa\u00edses o regiones sobre la admisibilidad de la evidencia digital en juicios internacionales. Por ejemplo:\n<ul class=\"lista\">\n<li>Tratados de Asistencia Legal Mutua (<a href=\"https:\/\/en.wikipedia.org\/wiki\/Mutual_legal_assistance_treaty\" target=\"_blank\" rel=\"nofollow noopener\">MLAT<\/a>) para el intercambio de informaci\u00f3n y pruebas en investigaciones criminales.<\/li>\n<li>Reglamento sobre pruebas electr\u00f3nicas de la Uni\u00f3n Europea (<a href=\"https:\/\/www.eurojust.europa.eu\/publication\/eu-electronic-evidence-legislative-package\" target=\"_blank\" rel=\"nofollow noopener\">European Union&#8217;s e-Evidence Regulation<\/a>) que permite solicitar pruebas digitales a proveedores de servicios en otros estados miembros.<\/li>\n<li>Iniciativa de INTERPOL contra los delitos cibern\u00e9ticos (<a href=\"https:\/\/www.interpol.int\/Crimes\/Cybercrime\" target=\"_blank\" rel=\"nofollow noopener\">Cybercrime Initiative<\/a>) para coordinar los esfuerzos internacionales encaminados a combatir los delitos cibern\u00e9ticos.<\/li>\n<\/ul>\n<\/li>\n<li>Acuerdos bilaterales entre pa\u00edses para compartir evidencia digital y colaborar en investigaciones de delitos cibern\u00e9ticos. Ejemplos:\n<ul class=\"lista\">\n<li><a href=\"https:\/\/questions-statements.parliament.uk\/written-statements\/detail\/2023-12-19\/hlws151#:~:text=The%20Agreement%20allows%20UK%20agencies%20to%20submit%20requests,and%20messaging%20services%2C%20located%20in%20the%20United%20States.\" target=\"_blank\" rel=\"nofollow noopener\">UK-US Data Access Agreement<\/A>, el acuerdo entre el Reino Unido y los EUA para solicitar directamente datos electr\u00f3nicos a los proveedores de telecomunicaciones del otro pa\u00eds, combatiendo el terrorismo y la explotaci\u00f3n infantil.<\/li>\n<li><a href=\"https:\/\/www.crossborderdataforum.org\/the-legal-nature-of-the-uk-us-cloud-agreement\/\" target=\"_blank\" rel=\"nofollow noopener\">CLOUD Act Agreement<\/a> permite a EUA y Reino Unido eliminar las barreras legales tradicionales y acceder a la evidencia electr\u00f3nica almacenada en las jurisdicciones de cada una.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Pol\u00edticas nacionales de ciberseguridad:<\/strong> Muchos pa\u00edses tienen sus propios marcos legales espec\u00edficos para regular la investigaci\u00f3n forense digital, brindando soporte a la ciberseguridad y los procedimientos legales. Ejemplos:\n<ul class=\"lista\">\n<li><a href=\"https:\/\/www.nist.gov\/cyberframework\" target=\"_blank\" rel=\"nofollow noopener\">NIST Cybersecurity Framework<\/A> de EUA para reducir el riesgo cibern\u00e9tico con mediante identificaci\u00f3n, protecci\u00f3n detecci\u00f3n, respuesta y recuperaci\u00f3n.<\/li>\n<li><a href=\"https:\/\/gdpr-info.eu\/\" target=\"_blank\" rel=\"nofollow noopener\">GDPR<\/a> (General Data Protection Regulation) de la Uni\u00f3n Europea para proteger los datos personales.<\/li>\n<li>En India, <a href=\"https:\/\/www.clearias.com\/national-cyber-security-policy-2013\/\" target=\"_blank\" rel=\"nofollow noopener\">National Cyber Security Policy <\/A>(NCSP) para proteger el ciberespacio promoviendo la concienciaci\u00f3n, el fortalecimiento de la infraestructura y la colaboraci\u00f3n entre sectores privados y p\u00fablicos.<\/li>\n<li>En Jap\u00f3n, <a href=\"https:\/\/www.nisc.go.jp\/eng\/pdf\/cs-strategy-en-pamphlet.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Cybersecurity Strategy<\/a> para la protecci\u00f3n de la infraestructura cr\u00edtica y la promoci\u00f3n del desarrollo e investigaci\u00f3n en materia de ciberseguridad.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"3\">Principios fundamentales<\/h2>\n<p>En la Inform\u00e1tica Forense, existen principios fundamentales que garantizan la integridad y confiabilidad de la evidencia digital. Estos principios sirven para guiar un trabajo meticuloso en la recopilaci\u00f3n, el an\u00e1lisis y la preservaci\u00f3n de los datos con fines legales y de investigaci\u00f3n, tales como:<\/p>\n<ul class=\"lista\">\n<li><strong>Integridad:<\/strong> Garantizar que los datos permanezcan inalterados desde el momento de recolecci\u00f3n hasta la presentaci\u00f3n ante el tribunal. Esto incluye la cadena de custodia (qu\u00e9 se recopil\u00f3, cu\u00e1ndo y qui\u00e9n recibe, preserva, etc.) para asegurar una evidencia intacta, con calidad y admisible ante la ley.<\/li>\n<li><strong>Documentaci\u00f3n y estandarizaci\u00f3n de procesos:<\/strong> Mantener registros detallados de todos los procedimientos y los hallazgos para mantener una cadena de custodia clara y procesos consistentes.<\/li>\n<li><strong>Preservaci\u00f3n:<\/strong> Salvaguardar la evidencia digital, buscando evitar la p\u00e9rdida o corrupci\u00f3n de los datos recopilados.<\/li>\n<li><strong>An\u00e1lisis:<\/strong> Examinar de forma sistem\u00e1tica los datos para descubrir informaci\u00f3n y patrones relevantes.<\/li>\n<\/ul>\n<h2 id=\"4\">Aplicaciones en ciberseguridad y resoluci\u00f3n de incidentes<\/h2>\n<p>La Investigaci\u00f3n forense es de suma importancia no solo para la investigaci\u00f3n criminal sino para los esfuerzos encaminados al reforzamiento de la ciberseguridad con grandes desaf\u00edos en tiempos digitales. Veamos algunos ejemplos:<\/p>\n<h3>Protecci\u00f3n contra amenazas internas<\/h3>\n<p>Un ejemplo claro y com\u00fan es la filtraci\u00f3n de datos confidenciales por parte de alg\u00fan empleado insatisfecho. Con las herramientas adecuadas, se puede detectar el acceso no autorizado a archivos sensibles fuera del horario laboral y obtener la evidencia de transferencia de datos a dispositivos externos. El equipo forense puede analizar los registros de actividad inusual para identificar al usuario responsable y, mediante la cadena de custodia, tener los elementos claros y consistentes para un proceso legal.<\/p>\n<h3>Investigaci\u00f3n de ciberataques<\/h3>\n<p>Ante el crecimiento de ataques de <a href=\"https:\/\/pandorafms.com\/es\/it-topics\/que-es-malware-como-prevenirlo\/\" target=\"_blank\" rel=\"noopener\">malware<\/A>, la investigaci\u00f3n forense puede ayudar al an\u00e1lisis de un incidente de ransomware, desde la detecci\u00f3n del ataque (qu\u00e9 sistemas han sido comprometidos); las acciones para aislar los sistemas o dispositivos afectados para que no siga propag\u00e1ndose, hasta el an\u00e1lisis del malware (entender su naturaleza: origen, m\u00e9todo de propagaci\u00f3n, etc.); el rastreo del cibercriminal (rastreando direcciones IP e indicadores que conduzcan al atacante); hasta la generaci\u00f3n de informes con hallazgos y recomendaciones para corregir y fortalecer la seguridad, as\u00ed como prevenir futuros ataques.<\/p>\n<h3>Cumplimiento normativo y auditor\u00edas<\/h3>\n<p>La Investigaci\u00f3n Forense resulta eficaz en la investigaci\u00f3n sobre la violaci\u00f3n sobre los datos personales. Los expertos forenses investigan el incidente e identifican a los responsables, adem\u00e1s de asegurar que la empresa implemente medidas para cumplir con leyes como GDPR. Tambi\u00e9n la Investigaci\u00f3n Forense ayuda a comprobar que las pol\u00edticas internas y los procedimientos operativos est\u00e9n bajo las regulaciones aplicables, evitando sanciones legales.<\/p>\n<h3>Resoluci\u00f3n de incidentes mediante an\u00e1lisis digital<\/h3>\n<p>La investigaci\u00f3n forense y la resoluci\u00f3n de incidentes mediante an\u00e1lisis digital son procesos integrados en la gesti\u00f3n de seguridad inform\u00e1tica. Esto es porque la investigaci\u00f3n forense digital permite la recopilaci\u00f3n de pruebas (ejemplo: creaci\u00f3n de im\u00e1genes forenses de dispositivos afectados), el an\u00e1lisis detallado para rastrear la <a href=\"https:\/\/pandorafms.com\/blog\/es\/analisis-de-causa-raiz-explicado-definicion-ejemplos-y-metodos\/\" target=\"_blank\" rel=\"noopener\">causa ra\u00edz<\/a> del incidente y as\u00ed poder identificar al atacante (mediante an\u00e1lisis del malware, rastreo de IPs y correlaci\u00f3n de eventos). Una vez llevado a cabo la investigaci\u00f3n, se procede a la gesti\u00f3n y resoluci\u00f3n de incidentes mediante el an\u00e1lisis digital implementado:<\/p>\n<ul class=\"lista\">\n<li><strong>Respuesta inmediata:<\/strong> Aislando sistemas comprometidos y buscando detener el ataque en curso para minimizar los da\u00f1os.<\/li>\n<li><strong>Remediaci\u00f3n:<\/strong> Reparando vulnerabilidades y restaurando sistemas afectados, adem\u00e1s de asegurarse de que est\u00e9n protegidos contra futuros ataques.<\/li>\n<li><strong>Lecciones aprendidas:<\/strong> Usando los hallazgos forenses para implementar medidas preventivas, como mejorar las configuraciones de seguridad o capacitar al personal.<\/li>\n<\/ul>\n<h2 id=\"5\">Fases de una investigaci\u00f3n forense digital<\/h2>\n<h3>Identificaci\u00f3n y clasificaci\u00f3n de evidencia<\/h3>\n<p>La investigaci\u00f3n forense inform\u00e1tica comienza con la identificaci\u00f3n de los recursos y dispositivos o <a href=\"https:\/\/pandorafms.com\/es\/it-topics\/que-es-un-endpoint\/\" target=\"_blank\" rel=\"noopener\">endpoints<\/a> (PC, lap top, celulares, tablets, etc.) que contienen los datos que ser\u00e1n objeto de la investigaci\u00f3n. Estos dispositivos son confiscados y sellados para evitar cualquier manipulaci\u00f3n de datos. Si los datos se almacenan en un servidor, una red o una nube, se debe garantizar que el acceso a ellos est\u00e9 restringido \u00fanicamente al equipo de investigaci\u00f3n.<\/p>\n<h3>Adquisici\u00f3n y preservaci\u00f3n de datos<\/h3>\n<p>El experto o analista forense emplea t\u00e9cnicas para recuperar cualquier dato relevante para la investigaci\u00f3n. Estos datos se resguardan de manera segura, adem\u00e1s de crear una r\u00e9plica digital o \u201cimagen forense\u201d de los datos relevantes. Los datos se usar\u00e1n para el an\u00e1lisis y revisi\u00f3n.<\/p>\n<h3>An\u00e1lisis y correlaci\u00f3n de eventos<\/h3>\n<p>En esta fase, los expertos forenses se apoyan en herramientas y metodolog\u00edas para recuperar datos relevantes y examinarlos, buscando evidencias que sugieran uso indebido o delito; tambi\u00e9n puede ser necesario aplicar t\u00e9cnicas como:<\/p>\n<ul class=\"lista\">\n<li><a href=\"https:\/\/techlib.net\/techedu\/stegano\/\" target=\"_blank\" rel=\"noopener\">Esteganograf\u00eda inversa<\/a> para extraer informaci\u00f3n oculta al observar el hash o la cadena de caracteres detr\u00e1s de una imagen u otro dato.<\/li>\n<li>Recuperaci\u00f3n de datos o tallado de archivos eliminados mediante la b\u00fasqueda de cualquier fragmento que se haya dejado atr\u00e1s.<\/li>\n<li>An\u00e1lisis en vivo con el cual se localizan, analizan y extraen los datos vol\u00e1tiles que se guardan en la memoria RAM o cach\u00e9 cuando el sistema operativo est\u00e1 funcionando o en vivo dentro de un laboratorio forense.<\/li>\n<li>B\u00fasquedas por palabras clave para encontrar y examinar datos borrados y que son relevantes para la investigaci\u00f3n.<\/li>\n<li>An\u00e1lisis cruzado (<a href=\"https:\/\/forensics.wiki\/cross_drive_analysis\/\" target=\"_blank\" rel=\"noopener\">Cross-drive analysis<\/A>, CDA), que es una t\u00e9cnica de extracci\u00f3n que permite a los investigadores examinar datos de diversas fuentes al mismo tiempo.<\/li>\n<\/ul>\n<h3>Documentaci\u00f3n<\/h3>\n<p>Al finalizar el an\u00e1lisis, los resultados de la investigaci\u00f3n se documentan de manera que se facilite la visualizaci\u00f3n del proceso completo de investigaci\u00f3n y sus conclusiones, incluyendo una cronolog\u00eda de las acciones que provocaron el incidente o ataque.<\/p>\n<h3>Presentaci\u00f3n<\/h3>\n<p>Los resultados se presentan ante un comit\u00e9 (o tribunal) que decidir\u00e1 c\u00f3mo proceder (con una demanda o queja interna). Los investigadores forense pueden actuar como testigos expertos, proporcionando un resumen y una presentaci\u00f3n de la evidencia recopilada y sus conclusiones.<\/p>\n<h4>Fases de una investigaci\u00f3n forense<\/h4>\n<p><img decoding=\"async\" class=\"imgpostcapture lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/pandorafms.com\/wp-content\/uploads\/2025\/04\/cyber-forensics-graph-pfms-it-topics.png\"><\/p>\n<h2 id=\"6\">Desaf\u00edos actuales en inform\u00e1tica forense<\/h2>\n<p>La evoluci\u00f3n de la tecnolog\u00eda es en s\u00ed un gran desaf\u00edo, ya que sigue evolucionando a pasos acelerados y esto tambi\u00e9n conlleva complejidades legales. Los desaf\u00edos que te recomendamos tener en mente son:<\/p>\n<ul class=\"lista\">\n<li><strong>Encriptaci\u00f3n y dispositivos IoT<\/Strong><br \/>\nLos algoritmos de encriptaci\u00f3n avanzados y los distintos sistemas operativos y protocolos hacen que la recolecci\u00f3n y el an\u00e1lisis de evidencia sea un proceso tortuoso y que puede consumir tiempo de tu equipo.<\/li>\n<li><strong>Avances en t\u00e1cticas de ciberdelincuentes<\/Strong><br \/>\nEl malware ser\u00e1 m\u00e1s sofisticado y ser\u00e1 lanzado a ataques dirigidos, lo que demandar\u00e1 expertos forenses constantemente actualizados.<\/li>\n<li><strong>Adaptaci\u00f3n a entornos cloud y m\u00f3viles<\/Strong><br \/>\nLa descentralizaci\u00f3n de los datos en cloud y dispositivos pueden ubicarse en servidores remotos e incluso globales, lo cual dificulta el acceso y la preservaci\u00f3n de la evidencia digital.<br \/>\nOtros desaf\u00edos son la escasez de personal experto en investigaci\u00f3n forense y la necesidad de capacitarse para estar a la par de la evoluci\u00f3n de la tecnolog\u00eda y los m\u00e9todos de ataque del cibercrimen. Tambi\u00e9n las leyes de protecci\u00f3n de datos y privacidad var\u00edan entre pa\u00edses y pueden limitar el acceso a informaci\u00f3n cr\u00edtica en los casos de una investigaci\u00f3n internacional.<br \/>\nLo que te recomendamos es acercarte a tu aliado tecnol\u00f3gico para obtener el apoyo en conocimiento de tecnolog\u00edas y la experiencia con las mejores pr\u00e1cticas en investigaci\u00f3n forense.<\/li>\n<\/ul>\n<h2 id=\"7\">Gesti\u00f3n del cambio en Project Management<\/h2>\n<p>Definitivamente, el \u00e9xito de la investigaci\u00f3n forense se basa en las herramientas y las plataformas adecuadas, tales como:<\/p>\n<h3>SIEM y an\u00e1lisis de registros<\/h3>\n<p>La gesti\u00f3n de eventos e informaci\u00f3n de seguridad (<a href=\"https:\/\/pandorafms.com\/es\/it-topics\/siem\/\" target=\"_blank\" rel=\"noopener\">SIEM<\/a>) y el an\u00e1lisis de registros son fundamentales para detectar, investigar y mitigar incidentes de seguridad. Por un lado, un SIEM permite la recopilaci\u00f3n centralizada de registros o logs de m\u00faltiples fuentes (servidores, dispositivos de red y aplicaciones) dando una visi\u00f3n integral sobre la actividad del sistema. Con esta informaci\u00f3n, se puede implementar la correlaci\u00f3n de eventos mediante reglas y algoritmos para asocian eventos aparentemente aislados, lo que ayuda a identificar patrones sospechosos que podr\u00edan se\u00f1alar un incidente de seguridad. Tambi\u00e9n, el SIEM puede generan alertas autom\u00e1ticas cuando se detectan anomal\u00edas, permitiendo actuar r\u00e1pidamente.<br \/>\nPor otro lado, el an\u00e1lisis de registros en la investigaci\u00f3n forense detalles clave para identificar la causa ra\u00edz, as\u00ed como tambi\u00e9n intentos de inicio de sesi\u00f3n fallidos o transferencias inusuales de datos. Tambi\u00e9n, el an\u00e1lisis de registros permite reconstruir la l\u00ednea de tiempo de un ataque, identificando los sistemas que se vieron comprometidos. Cabe mencionar que los registros detallados son de vital importancia para demostrar el cumplimiento con las regulaciones de seguridad y privacidad.<\/p>\n<h3>An\u00e1lisis de malware e ingenier\u00eda inversa<\/h3>\n<p>El an\u00e1lisis de malware permite identificar archivos sospechosos para determinar si contienen c\u00f3digo malicioso, para despu\u00e9s aplicar un an\u00e1lisis est\u00e1tico (estudiando el c\u00f3digo del malware sin ejecutarlo, utilizando desensambladores y herramientas de an\u00e1lisis de c\u00f3digo) para entender su estructura y funcionalidad; y el an\u00e1lisis din\u00e1mico (ejecutando el malware en un entorno controlado o sandbox) para observar su comportamiento en conexiones de red, modificaciones de archivos y\/o procesos creados. Con esto, se generan los indicadores de compromiso (IoCs) como patrones \u00fanicos del malware (direcciones IP o nombres de archivos) para la detecci\u00f3n y prevenci\u00f3n de futuros ataques.<br \/>\nLa ingenier\u00eda inversa se aplica para descompilar el software malicioso (en un formato legible para entender su funcionamiento y vulnerabilidades); e implementar la reconstrucci\u00f3n de algoritmos (con m\u00e9todos usados por el malware para cifrar datos o evadir detecci\u00f3n) para desarrollar la defensa y contraataque. Con esto, se puede identificar a los autores del ataque y vincularlos con grupos de atacantes.<\/p>\n<h3>Protecci\u00f3n de endpoints y detecci\u00f3n de intrusos<\/h3>\n<p>La investigaci\u00f3n forense digital requiere de <a href=\"https:\/\/pandorafms.com\/es\/monitorizacion-para-msp-soc\/\" target=\"_blank\" rel=\"noopener\">monitorizaci\u00f3n<\/A> continua, supervisando constantemente los dispositivos para detectar actividades sospechosas. Tambi\u00e9n, mediante el an\u00e1lisis del uso de los endpoints y herramientas de seguridad (incluso apoy\u00e1ndose en la Inteligencia Artificial) se puede bloquear el malware a\u00fan antes de afectar a los sistemas de la empresa. Tambi\u00e9n, la informaci\u00f3n de los endpoints protegidos puede proporcionar registros valiosos para la investigaci\u00f3n forense. Los sistemas de Detecci\u00f3n de Intrusos y de Prevenci\u00f3n de Intrusos (IDS\/IPS) identifican y bloquean actividades maliciosas en la red, como ataques de denegaci\u00f3n de servicio (<a href=\"https:\/\/pandorafms.com\/es\/it-topics\/ataque-ddos-seguridad\/\" target=\"_blank\" rel=\"noopener\">DDoS<\/a>). Adicionalmente, los registros de tr\u00e1fico de red recopilados por <a href=\"https:\/\/pandorafms.com\/es\/it-topics\/siem\/\" target=\"_blank\" rel=\"noopener\">IDS\/IPS<\/a> ayudan a rastrear la fuente de un ataque durante una investigaci\u00f3n forense. Con sistemas avanzados de SIEM y monitorizaci\u00f3n se puede correlacionar eventos de posible intrusi\u00f3n para obtener una mayor contextualizaci\u00f3n de un evento de seguridad.<\/p>\n<h3>Forensia en la nube y dispositivos m\u00f3viles<\/h3>\n<p>La nube implica tener los datos almacenados en m\u00faltiples servidores y ubicaciones geogr\u00e1ficas, lo que complica la recuperaci\u00f3n y an\u00e1lisis de los datos de los dispositivos para su an\u00e1lisis. Es importante que se implementen<br \/>\nt\u00e9cnicas avanzadas para garantizar que los datos recuperados de la nube no se alteren durante el proceso de investigaci\u00f3n. Por ello, los forenses deben usar herramientas capaces de recuperar informaci\u00f3n de smartphones, tablets, laptop, etc. incluyendo mensajes (email, texto), registros de llamadas y datos de aplicaciones.<\/p>\n<h3>Inteligencia artificial aplicada a la inform\u00e1tica forense<\/h3>\n<p>La inteligencia artificial (IA) se ha convertido en un poderoso colaborador digital en la inform\u00e1tica forense por su capacidad de an\u00e1lisis predictivo en gran volumen y diversidad de fuentes; la automatizaci\u00f3n de tareas repetitivas; el reconocimiento de patrones o anomal\u00edas; el an\u00e1lisis avanzado de malware, incluyendo la creaci\u00f3n de escenarios hipot\u00e9ticos, tendencias y conexiones que podr\u00edan ser dif\u00edciles de identificar para los forenses humanos. Por lo que la IA est\u00e1 transformando la inform\u00e1tica forense al agilizar procesos y mejorar la precisi\u00f3n en la investigaci\u00f3n digital.<\/p>\n<h2 id=\"8\">Integraci\u00f3n con la respuesta a incidentes (DFIR)<\/h2>\n<p>La inform\u00e1tica forense con la respuesta a incidentes (Digital Forensics and Incident Response, <a href=\"https:\/\/ciberseguridadtips.com\/dfir-analisis-forense-respuesta-ante-incidentes\/\" target=\"_blank\" rel=\"nofollow noopener\">DFIR<\/a>) emplea dos disciplinas para abordar las ciberamenazas: la  detecci\u00f3n y mitigaci\u00f3n de amenazas que permite la recopilaci\u00f3n, preservaci\u00f3n y an\u00e1lisis de la evidencia digital para reconstruir incidentes y apoyar a investigaciones legales, auditor\u00edas de cumplimiento y mejoras en la estrategia de seguridad; la automatizaci\u00f3n en respuesta a incidentes que aprovecha el an\u00e1lisis realizado para poder automatizar las alertas y la respuesta no solo en tiempo real, sino tambi\u00e9n de manera proactiva.<br \/>\nPara emprender la labor forense con tu equipo experto (analista forense de c\u00f3mputo o <a href=\"https:\/\/www.cyberdegrees.org\/jobs\/computer-forensics\/\" target=\"_blank\" rel=\"noopener nofollow\">computer forensics analyst\/ investigator<\/A>,  ingeniero o <a href=\"https:\/\/www.unir.net\/revista\/ingenieria\/informatica-forense\/\" target=\"_blank\" rel=\"nofollow noopener\">inform\u00e1tico forense<\/A>, analista de ciberseguridad, consultores legales en tecnolog\u00eda, <a href=\"https:\/\/expertpericial.com\/perito-informatico-forense-un-experto-clave-en-la-lucha-contra-los-delitos-informaticos\/\" target=\"_blank\" rel=\"nofollow noopener\">peritos forenses digitales<\/a>) desde el \u00e1rea de seguridad o un centro de operaciones de seguridad (SOC, <a href=\"https:\/\/www.webopedia.com\/definitions\/security-operations-center-soc\/\" target=\"_blank\" rel=\"nofollow noopener\">Security Operations Center<\/a>), siempre hay que estar atentos a la evoluci\u00f3n de las t\u00e9cnicas, procedimientos y m\u00e9todos anti-forenses del cibercrimen. Para estas disciplinas, los datos de la monitorizaci\u00f3n en tiempo real y contextualizado son el oro que marcar\u00e1n la diferencia de una estrategia de ciberseguridad integrada y eficiente.<\/p>\n<h2 id=\"9\">El rol de Pandora FMS en la inform\u00e1tica forense<\/h2>\n<p>Pandora FMS es una soluci\u00f3n completa de monitorizaci\u00f3n de todos los elementos de la infraestructura de TI, aprovechando la informaci\u00f3n obtenida directamente de las fuentes de datos y los agentes software en los equipos y los dispositivos, independientemente de su ubicaci\u00f3n dentro de la empresa o de manera extendida tales como entornos cloud, Edge Computing o dispositivos IoT, con las siguientes ventajas para quien emprende la inform\u00e1tica forense:<\/p>\n<ul class=\"lista\">\n<li><strong>Integraci\u00f3n con SIEM:<\/strong> Si ya eres usuario de Pandora FMS, solo hay que activar el SIEM server para recopilar la informaci\u00f3n de los eventos desde los agentes, as\u00ed de manera autom\u00e1tica obtendr\u00e1s un SIEM robusto para la labor forense de tu equipo. Sin la necesidad de herramientas adicionales para obtener informaci\u00f3n clave.<\/li>\n<li><strong>Monitorizaci\u00f3n avanzada y correlaci\u00f3n de eventos:<\/strong> La integraci\u00f3n de Pandora FMS y SIEM permite combinar eventos de seguridad con la monitorizaci\u00f3n en tiempo real, incluyendo datos hist\u00f3ricos a largo plazo y logs en crudo, proporcionando una visi\u00f3n m\u00e1s completa para tu equipo experto. Adem\u00e1s, mediante reglas p\u00fablicas y editables de Pandora SIEM puedes enriquecer la informaci\u00f3n sobre los eventos de seguridad, creando correlaciones avanzadas que facilitan la detecci\u00f3n de patrones sospechosos.<\/li>\n<li><strong>Recopilaci\u00f3n de evidencia digital:<\/strong> Los datos en tiempo real, seguros y consistentes permiten recabar la evidencia confiable en informes claros sobre los eventos de seguridad, no solo para tu equipo, sino tambi\u00e9n para tus clientes con el fin de atender necesidades de auditor\u00eda y cumplimiento regulatorio, as\u00ed como tambi\u00e9n para procesos legales.<\/li>\n<li><strong>Beneficios en la respuesta a incidentes:<\/strong> El tener una misma plataforma con total observabilidad agiliza y hace m\u00e1s eficiente la respuesta del equipo de seguridad y los expertos forenses ante incidentes que requieren respuestas inmediatas, coordinadas y certeras, adem\u00e1s de dar los elementos confiables para emprender la orquestaci\u00f3n y automatizaci\u00f3n de seguridad (SOAR) junto con las mejoras en las estrategias de seguridad desde un enfoque multidisciplinario.<\/li>\n<\/ul>\n<p>Te invito a probar esta soluci\u00f3n, solicitando tu trial en este <a href=\"https:\/\/pandorafms.com\/es\/trial-gratis\/\" target=\"_blank\" rel=\"noopener\">link<\/a>.[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjM2MjI3MCJ9fQ==@\u00bb button_text=\u00bb\u2190 Regresar a IT Topics\u00bb button_alignment=\u00bbleft\u00bb _builder_version=\u00bb4.22.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb1em\u00bb button_text_color=\u00bb#0C312F\u00bb button_bg_color=\u00bb#FFFFFF\u00bb button_bg_color_gradient_direction=\u00bb90deg\u00bb button_bg_color_gradient_stops=\u00bb#82B92E 0%|#3CB92E 100%\u00bb button_bg_color_gradient_start=\u00bb#82B92E\u00bb button_bg_color_gradient_end=\u00bb#3CB92E\u00bb button_border_width=\u00bb1px\u00bb button_border_color=\u00bb#eaeaea\u00bb button_border_radius=\u00bb100px\u00bb button_use_icon=\u00bboff\u00bb z_index=\u00bb0&#8243; custom_margin=\u00bb60px||0px||false|false\u00bb custom_padding=\u00bb10px|50px|10px|50px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb10px|20px|10px|20px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb custom_css_main_element=\u00bbright:0!important;||font-family:%22Pandora-Bold%22!important;\u00bb global_module=\u00bb367749&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color_gradient_start__hover=\u00bb#eaeaea\u00bb button_bg_color_gradient_end__hover=\u00bb#f4f4f4&#8243; button_bg_color__hover=\u00bb#eaeaea\u00bb button_bg_enable_color__hover=\u00bbon\u00bb button_bg_use_color_gradient__hover=\u00bbon\u00bb button_bg_color_gradient_stops__hover=\u00bb#eaeaea 0%|#f4f4f4 100%\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbFinal CTA\u00bb _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#161327&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(22,19,39,0.5) 17%|rgba(22,19,39,0.5) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/pandorafms.com\/wp-content\/uploads\/2024\/01\/img-banner-it-topics-resumen-de-producto.webp\u00bb background_position=\u00bbtop_center\u00bb z_index=\u00bb1&#8243; max_width=\u00bb1080px\u00bb max_width_tablet=\u00bb98%\u00bb max_width_phone=\u00bb98%\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb80px||80px||true|false\u00bb custom_padding=\u00bb40px|20px|160px|20px|false|true\u00bb custom_padding_tablet=\u00bb40px|0px|120px|0px|false|true\u00bb custom_padding_phone=\u00bb40px|0px|120px|0px|false|true\u00bb scroll_scaling=\u00bb40|55|85|100|100%|120%|100%\u00bb motion_trigger_start=\u00bbtop\u00bb background_last_edited=\u00bboff|desktop\u00bb border_radii=\u00bboff|20px|20px|20px|20px\u00bb border_color_all=\u00bb#ffffff\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_vertical=\u00bb0px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bb#506da0&#8243; global_module=\u00bb367405&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb550px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.22.0&#8243; _module_preset=\u00bbdefault\u00bb header_2_font_size=\u00bb2em\u00bb text_orientation=\u00bbcenter\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb0px||20px||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p class=\"h2-w\">\u00bfPuede una sola herramienta tener una visibilidad global?<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMzMDcyMSJ9fQ==@\u00bb button_text=\u00bb\u00a1Desc\u00fabrelo!\u00bb button_alignment=\u00bbcenter\u00bb button_alignment_tablet=\u00bbcenter\u00bb button_alignment_phone=\u00bbcenter\u00bb button_alignment_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.22.0&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb1em\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_use_color_gradient=\u00bbon\u00bb button_bg_color_gradient_direction=\u00bb90deg\u00bb button_bg_color_gradient_stops=\u00bb#82B92E 0%|#3CB92E 100%\u00bb button_bg_color_gradient_start=\u00bb#82B92E\u00bb button_bg_color_gradient_end=\u00bb#3CB92E\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb100px\u00bb button_use_icon=\u00bboff\u00bb z_index=\u00bb0&#8243; custom_margin=\u00bb40px||0px||false|false\u00bb custom_padding=\u00bb10px|40px|10px|40px|true|true\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb15px|15px|15px|15px|true|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb custom_css_main_element=\u00bbright:0!important;||font-family:%22Pandora-Bold%22!important;\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|hover\u00bb button_bg_color_gradient_start__hover=\u00bb#05201F\u00bb button_bg_color_gradient_end__hover=\u00bb#05201F\u00bb button_bg_color_gradient_stops__hover=\u00bb#181818 0%|#181818 58%|#181818 100%\u00bb button_bg_use_color_gradient__hover=\u00bbon\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secciones Definici\u00f3n y relevancia en ciberseguridad Evoluci\u00f3n de la inform\u00e1tica forense Principios fundamentales Aplicaciones en ciberseguridad y resoluci\u00f3n de incidentes Fases de una investigaci\u00f3n forense digital Desaf\u00edos actuales en inform\u00e1tica forense Herramientas y t\u00e9cnicas clave Integraci\u00f3n con la respuesta a incidentes (DFIR) El rol de Pandora FMS en la inform\u00e1tica forense Definici\u00f3n y relevancia en [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":395997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[7754,3506],"tags":[],"class_list":["post-395964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciberseguridad","category-it-topics"],"_links":{"self":[{"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/posts\/395964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/comments?post=395964"}],"version-history":[{"count":8,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/posts\/395964\/revisions"}],"predecessor-version":[{"id":396074,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/posts\/395964\/revisions\/396074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/media\/395997"}],"wp:attachment":[{"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/media?parent=395964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/categories?post=395964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pandorafms.com\/es\/wp-json\/wp\/v2\/tags?post=395964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}